{"id":51774,"date":"2023-11-07T09:06:31","date_gmt":"2023-11-07T08:06:31","guid":{"rendered":"http:\/\/blogs.emuca.com\/nblog\/?p=51774"},"modified":"2023-11-07T09:10:58","modified_gmt":"2023-11-07T08:10:58","slug":"perto-de-um-local-inteligente-novos-sensores","status":"publish","type":"post","link":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/","title":{"rendered":"Perto de um local inteligente. Novos sensores"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"51774\" class=\"elementor elementor-51774 elementor-51765\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-301e7f17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"301e7f17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5fd5a5c1\" data-id=\"5fd5a5c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e41ee26 elementor-widget elementor-widget-text-editor\" data-id=\"e41ee26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Num mundo cada vez mais conectado, a incorpora\u00e7\u00e3o de sensores em sua casa ou noutro local \u00e9 uma escolha sensata. Estes dispositivos revolucion\u00e1rios n\u00e3o s\u00f3 acrescentam comodidade \u00e0 sua vida, como tamb\u00e9m melhoram significativamente a efici\u00eancia energ\u00e9tica.<\/p>\n<p>Se est\u00e1 \u00e0 procura de uma forma mais inteligente e eficiente de iluminar o seu espa\u00e7o, a Emuca aposta nos sensores sem fios como a solu\u00e7\u00e3o perfeita. Leve a ilumina\u00e7\u00e3o da sua casa ou local de trabalho a um novo n\u00edvel com os nossos novos sensores Wirly e Dot.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f77c35c elementor-widget elementor-widget-html\" data-id=\"f77c35c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-9c54be69-532c-4017-a9e9-81b2071afef1\"><span class=\"hs-cta-node hs-cta-9c54be69-532c-4017-a9e9-81b2071afef1\" id=\"hs-cta-9c54be69-532c-4017-a9e9-81b2071afef1\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/4071763\/9c54be69-532c-4017-a9e9-81b2071afef1\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-9c54be69-532c-4017-a9e9-81b2071afef1\" style=\"border-width:0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4071763\/9c54be69-532c-4017-a9e9-81b2071afef1.png\"  alt=\"Nueva llamada a la acci\u00f3n\"\/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(4071763, '9c54be69-532c-4017-a9e9-81b2071afef1', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92283bd elementor-widget elementor-widget-spacer\" data-id=\"92283bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24d09ae elementor-widget elementor-widget-text-editor\" data-id=\"24d09ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>OS NOSSOS NOVOS SENSORES<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2985258 elementor-widget elementor-widget-text-editor\" data-id=\"2985258\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Sensores Wirly<\/h3><p>Os <b>sensores LED Wirly switch\/motion<\/b> 12V DC \/ 24V DC, 12V DC &#8211; 24V DC s\u00e3o uma solu\u00e7\u00e3o vers\u00e1til que lhe permite ligar ou desligar as luzes a partir de qualquer ponto da divis\u00e3o, sem necessidade de instala\u00e7\u00f5es el\u00e9ctricas complicadas. Com um alcance de 10 metros, este sensor tem duas fun\u00e7\u00f5es: como sensor de proximidade para ligar com a porta e como sensor de interrutor sem fios que lhe permite ligar, desligar e regular a intensidade da lumin\u00e1ria com facilidade. A sua mem\u00f3ria inteligente armazena a \u00faltima defini\u00e7\u00e3o selecionada, garantindo comodidade em qualquer altura.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a34e541 elementor-widget__width-auto elementor-widget elementor-widget-hotspot\" data-id=\"a34e541\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;520e76a&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/iluminacao\\\/conversores-e-sensores\\\/sensores-pt\\\/receptor-sensor-led-wirly-12v-dc--24v-dc\\\/receptor-sensor-led-wirly-12v-dc--24v-dc-12v-dc---24v-dc-plastico&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Cabo adaptador Miniled para AMP&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:46,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:21,&quot;sizes&quot;:[]},&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;hotspot_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;index&quot;:0,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null},{&quot;_id&quot;:&quot;0fd5801&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/iluminacao\\\/conversores-e-sensores\\\/sensores-pt\\\/receptor-sensor-led-wirly-12v-dc--24v-dc\\\/receptor-sensor-led-wirly-12v-dc--24v-dc-12v-dc---24v-dc-plastico&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Recetor 6 entradas Miniled + Cabo 1m&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:48,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:55,&quot;sizes&quot;:[]},&quot;index&quot;:1,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null},{&quot;_id&quot;:&quot;d112294&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/iluminacao\\\/conversores-e-sensores\\\/sensores-pt\\\/receptor-sensor-led-wirly-12v-dc--24v-dc\\\/receptor-sensor-led-wirly-12v-dc--24v-dc-12v-dc---24v-dc-plastico&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Distribuidor AMP 6 entradas&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:74,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:28,&quot;sizes&quot;:[]},&quot;index&quot;:2,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null}],&quot;tooltip_position&quot;:&quot;left&quot;,&quot;tooltip_trigger&quot;:&quot;mouseenter&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-direction&quot;,&quot;hotspot_sequenced_animation&quot;:&quot;no&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/elementor\/thumbs\/WIRLY2-scaled-qo3o5lrtc3keiz7py7gmx5h8abjit2at3s8ek4tub0.jpg\" title=\"WIRLY2\" alt=\"WIRLY2\" loading=\"lazy\" \/>\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-520e76a  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/iluminacao\/conversores-e-sensores\/sensores-pt\/receptor-sensor-led-wirly-12v-dc--24v-dc\/receptor-sensor-led-wirly-12v-dc--24v-dc-12v-dc---24v-dc-plastico\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__direction-mask e-hotspot--tooltip-position\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip   e-hotspot--fade-direction \" >\r\n\t\t\t\t\t\tCabo adaptador Miniled para AMP\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-0fd5801  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/iluminacao\/conversores-e-sensores\/sensores-pt\/receptor-sensor-led-wirly-12v-dc--24v-dc\/receptor-sensor-led-wirly-12v-dc--24v-dc-12v-dc---24v-dc-plastico\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__direction-mask e-hotspot--tooltip-position\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip   e-hotspot--fade-direction \" >\r\n\t\t\t\t\t\tRecetor 6 entradas Miniled + Cabo 1m\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-d112294  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/iluminacao\/conversores-e-sensores\/sensores-pt\/receptor-sensor-led-wirly-12v-dc--24v-dc\/receptor-sensor-led-wirly-12v-dc--24v-dc-12v-dc---24v-dc-plastico\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__direction-mask e-hotspot--tooltip-position\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip   e-hotspot--fade-direction \" >\r\n\t\t\t\t\t\tDistribuidor AMP 6 entradas\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-638ea9e elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-hotspot\" data-id=\"638ea9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;520e76a&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/iluminacao\\\/conversores-e-sensores\\\/sensores-pt\\\/transmissor-sensor-led-wirly-switchdimmer-interruptor-12v-dc--24v-dc\\\/transmissor-sensor-led-wirly-switchdimmer-interruptor-12v-dc--24v-dc-plastico&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Transmissor para sensor LED Wirly (interrutor)&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:43,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:29,&quot;sizes&quot;:[]},&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;hotspot_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;index&quot;:0,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null}],&quot;tooltip_position&quot;:&quot;left&quot;,&quot;tooltip_trigger&quot;:&quot;mouseenter&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-direction&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;hotspot_sequenced_animation&quot;:&quot;no&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"253\" height=\"231\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/11\/c.jpg\" class=\"attachment-full size-full wp-image-51955\" alt=\"\" \/>\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-520e76a  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/iluminacao\/conversores-e-sensores\/sensores-pt\/transmissor-sensor-led-wirly-switchdimmer-interruptor-12v-dc--24v-dc\/transmissor-sensor-led-wirly-switchdimmer-interruptor-12v-dc--24v-dc-plastico\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__direction-mask e-hotspot--tooltip-position\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip   e-hotspot--fade-direction \" >\r\n\t\t\t\t\t\tTransmissor para sensor LED Wirly (interrutor)\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd68047 elementor-widget__width-auto elementor-widget elementor-widget-hotspot\" data-id=\"fd68047\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;520e76a&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/iluminacao\\\/conversores-e-sensores\\\/sensores-pt\\\/transmissor--sensor-led-wirly-door-proximidade-12v-dc--24v-dc\\\/transmissor--sensor-led-wirly-door-proximidade-12v-dc--24v-dc-plastico&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Transmissor para sensor LED Wirly (proximidade)&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:49,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:19,&quot;sizes&quot;:[]},&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;hotspot_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;index&quot;:0,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null}],&quot;tooltip_position&quot;:&quot;left&quot;,&quot;tooltip_trigger&quot;:&quot;mouseenter&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-direction&quot;,&quot;hotspot_sequenced_animation&quot;:&quot;no&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/elementor\/thumbs\/8432393306193_c-qo3o5ol9gw3oi3gatyaeo0zw6pygrl65nbrfpn0p8w.jpg\" title=\"8432393306193_c\" alt=\"8432393306193_c\" loading=\"lazy\" \/>\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-520e76a  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/iluminacao\/conversores-e-sensores\/sensores-pt\/transmissor--sensor-led-wirly-door-proximidade-12v-dc--24v-dc\/transmissor--sensor-led-wirly-door-proximidade-12v-dc--24v-dc-plastico\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__direction-mask e-hotspot--tooltip-position\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip   e-hotspot--fade-direction \" >\r\n\t\t\t\t\t\tTransmissor para sensor LED Wirly (proximidade)\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd9830c elementor-widget elementor-widget-spacer\" data-id=\"dd9830c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-872c918 elementor-widget elementor-widget-spacer\" data-id=\"872c918\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d78887 elementor-widget elementor-widget-text-editor\" data-id=\"7d78887\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"font-family: Montserrat, sans-serif;\">Sensores Dot<\/h3><p>Os<b> sensores LED Dot \u00d812 e Dot \u00d816 com interrutor\/dimmer<\/b> s\u00e3o vers\u00e1teis e integram-se no mobili\u00e1rio com um design discreto. Permitem a liga\u00e7\u00e3o de v\u00e1rias luzes de 12V ou 24V DC a um \u00fanico conversor. Uma press\u00e3o breve liga ou desliga as luzes e uma press\u00e3o longa ajusta a intensidade da luz. T\u00eam uma fun\u00e7\u00e3o de mem\u00f3ria. Utilizam tecnologia capacitiva para uma dete\u00e7\u00e3o de toque precisa e s\u00e3o robustos. Estes dispositivos aumentam o conforto e a versatilidade da sua ilumina\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cfa63a elementor-widget elementor-widget-hotspot\" data-id=\"4cfa63a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;520e76a&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Distribuidor AMP 6 entradas&lt;\\\/p&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:78,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;hotspot_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;index&quot;:0,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null},{&quot;_id&quot;:&quot;0fd5801&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/iluminacao\\\/conversores-e-sensores\\\/sensores-pt\\\/sensor-led-dot-2-switchdimmer-interruptor-12v-dc--24v-dc\\\/sensor-led-dot-2-switchdimmer-interruptor-12v-dc--24v-dc-12v-dc---24v-dc-pintado-aluminio-plastico&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;LED Ponto \\u00d812 sensor t\\u00e1til + cabo de entrada\\\/sa\\u00edda 1,5m&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:28,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:53,&quot;sizes&quot;:[]},&quot;index&quot;:1,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null},{&quot;_id&quot;:&quot;7b58f3c&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/iluminacao\\\/conversores-e-sensores\\\/sensores-pt\\\/dot-switch-dimmer-interruptor-12v-dc-24v-dc-pt\\\/dot-switch-dimmer-interruptor-12v-dc-24v-dc-pt-5022825-6-12v-dc---24v-dc-12v-dc---24v-dc-36-w--12v-dc----72-w--24v-dc--cinza-metalizado&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;LED Ponto \\u00d816 sensor t\\u00e1til + cabo de entrada\\\/sa\\u00edda 1,5m&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:56,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:82,&quot;sizes&quot;:[]},&quot;index&quot;:2,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null},{&quot;_id&quot;:&quot;d112294&quot;,&quot;hotspot_tooltip_content&quot;:&quot;Conectores AMP e parafusos&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:72,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:19,&quot;sizes&quot;:[]},&quot;index&quot;:3,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null}],&quot;tooltip_position&quot;:&quot;left&quot;,&quot;tooltip_trigger&quot;:&quot;mouseenter&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-direction&quot;,&quot;hotspot_sequenced_animation&quot;:&quot;no&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/elementor\/thumbs\/todo-qo3o5olbwlojq3rrns0qw6om9edq33llewxs0fz5b4.jpg\" title=\"todo\" alt=\"todo\" loading=\"lazy\" \/>\r\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-520e76a  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__direction-mask e-hotspot--tooltip-position\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip   e-hotspot--fade-direction \" >\r\n\t\t\t\t\t\t<p>Distribuidor AMP 6 entradas<\/p>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/div>\r\n\r\n\t\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-0fd5801  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/iluminacao\/conversores-e-sensores\/sensores-pt\/sensor-led-dot-2-switchdimmer-interruptor-12v-dc--24v-dc\/sensor-led-dot-2-switchdimmer-interruptor-12v-dc--24v-dc-12v-dc---24v-dc-pintado-aluminio-plastico\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__direction-mask e-hotspot--tooltip-position\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip   e-hotspot--fade-direction \" >\r\n\t\t\t\t\t\tLED Ponto \u00d812 sensor t\u00e1til + cabo de entrada\/sa\u00edda 1,5m\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-7b58f3c  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/iluminacao\/conversores-e-sensores\/sensores-pt\/dot-switch-dimmer-interruptor-12v-dc-24v-dc-pt\/dot-switch-dimmer-interruptor-12v-dc-24v-dc-pt-5022825-6-12v-dc---24v-dc-12v-dc---24v-dc-36-w--12v-dc----72-w--24v-dc--cinza-metalizado\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__direction-mask e-hotspot--tooltip-position\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip   e-hotspot--fade-direction \" >\r\n\t\t\t\t\t\tLED Ponto \u00d816 sensor t\u00e1til + cabo de entrada\/sa\u00edda 1,5m\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<div class=\"e-hotspot elementor-repeater-item-d112294  e-hotspot--position-left e-hotspot--position-top   e-hotspot--circle\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__direction-mask e-hotspot--tooltip-position\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip   e-hotspot--fade-direction \" >\r\n\t\t\t\t\t\tConectores AMP e parafusos\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/div>\r\n\r\n\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c1d8ef elementor-widget elementor-widget-text-editor\" data-id=\"3c1d8ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Onde os aplicar<\/h2><p>Aqui est\u00e3o apenas algumas ideias, mas as possibilidades s\u00e3o infinitas. Os sensores sem fios Wirly e Dot oferecem-lhe uma forma discreta e eficiente de controlar a ilumina\u00e7\u00e3o em sua casa ou noutro local, proporcionando comodidade e poupan\u00e7a de energia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-992245f elementor-widget elementor-widget-accordion\" data-id=\"992245f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1601\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1601\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ilumina\u00e7\u00e3o autom\u00e1tica do corredor<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1601\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1601\"><p>Instale sensores Wirly nos corredores para que as luzes se acendam automaticamente quando algu\u00e9m se aproxima. Isto \u00e9 \u00fatil \u00e0 noite ou quando se tem as m\u00e3os ocupadas.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1602\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1602\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Controlo da ilumina\u00e7\u00e3o do arm\u00e1rio<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1602\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1602\"><p>Utilize o Sensor Dot nos seus sistemas de arruma\u00e7\u00e3o. A luz acende-se quando abre a porta, facilitando a procura de tudo o que precisa.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1603\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1603\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ilumina\u00e7\u00e3o economizadora de energia na despensa<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1603\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1603\"><p>Os sensores Wirly e Dot permitem-lhe ter uma ilumina\u00e7\u00e3o economizadora de energia na despensa. As luzes s\u00f3 se acendem quando se abre a porta, o que ajuda a poupar energia.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1604\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1604\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ilumina\u00e7\u00e3o suave no quarto<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1604\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1604\"><p>Utilize o Sensor Dot no seu quarto para uma ilumina\u00e7\u00e3o suave e regul\u00e1vel. Ideal para criar uma atmosfera relaxante antes de se deitar.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1605\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1605\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ilumina\u00e7\u00e3o da garagem ou da oficina<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1605\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1605\"><p>Instale sensores Wirly na garagem ou na oficina para que as luzes se acendam automaticamente quando entra, facilitando a procura de ferramentas ou a execu\u00e7\u00e3o de tarefas.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-297980d elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"297980d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/11\/8432393257433-cortada-scaled.jpg\" alt=\"8432393257433 cortada\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/11\/8432393257433__-1-scaled.jpg\" alt=\"8432393257433__\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/11\/AMBIENTE-LEVELUP-V-1-ALTA-scaled.jpg\" alt=\"AMBIENTE-LEVELUP-V-1-ALTA\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/08\/cajon-blog.jpg\" alt=\"cajon-blog\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/11\/barn-2__.jpg\" alt=\"barn 2__\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Num mundo cada vez mais conectado, a incorpora\u00e7\u00e3o de sensores em sua casa ou noutro local \u00e9 uma escolha sensata. Estes dispositivos revolucion\u00e1rios n\u00e3o s\u00f3 acrescentam comodidade \u00e0 sua vida, como tamb\u00e9m melhoram significativamente a efici\u00eancia energ\u00e9tica. Se est\u00e1 \u00e0 procura de uma forma mais inteligente e eficiente de iluminar o seu espa\u00e7o, a Emuca &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/\" class=\"more-link\">Continuar a ler <span class=\"screen-reader-text\">&#8220;Perto de um local inteligente. Novos sensores&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":52324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59,108,121],"tags":[1720,484],"class_list":["post-51774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-pt","category-novidades","category-tendencias","tag-puxadores-de-armario-pt-pt-2","tag-puxadores-de-gaveta","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perto de um local inteligente. Novos sensores - Emuca Blogue<\/title>\n<meta name=\"description\" content=\"Surpreenda-se com a inova\u00e7\u00e3o dos sensores sem fios Wirly e Dot 2 para uma ilumina\u00e7\u00e3o inteligente e eficiente. Dete\u00e7\u00e3o de proximidade, interrutor sem fios e controlo t\u00e1til preciso num \u00fanico dispositivo. Adapt\u00e1vel a m\u00faltiplas aplica\u00e7\u00f5es, transforme a sua ilumina\u00e7\u00e3o com estilo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perto de um local inteligente. Novos sensores - Emuca Blogue\" \/>\n<meta property=\"og:description\" content=\"Surpreenda-se com a inova\u00e7\u00e3o dos sensores sem fios Wirly e Dot 2 para uma ilumina\u00e7\u00e3o inteligente e eficiente. Dete\u00e7\u00e3o de proximidade, interrutor sem fios e controlo t\u00e1til preciso num \u00fanico dispositivo. Adapt\u00e1vel a m\u00faltiplas aplica\u00e7\u00f5es, transforme a sua ilumina\u00e7\u00e3o com estilo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/\" \/>\n<meta property=\"og:site_name\" content=\"Emuca blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EmucaGroup\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-07T08:06:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-07T08:10:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/10\/PORTADA-SENSORES.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emuca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emuca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/actualidad-pt\\\/perto-de-um-local-inteligente-novos-sensores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/actualidad-pt\\\/perto-de-um-local-inteligente-novos-sensores\\\/\"},\"author\":{\"name\":\"Emuca\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/person\\\/81560ca037d9c1ed19744a85ef9cbe2a\"},\"headline\":\"Perto de um local inteligente. Novos sensores\",\"datePublished\":\"2023-11-07T08:06:31+00:00\",\"dateModified\":\"2023-11-07T08:10:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/actualidad-pt\\\/perto-de-um-local-inteligente-novos-sensores\\\/\"},\"wordCount\":574,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/actualidad-pt\\\/perto-de-um-local-inteligente-novos-sensores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PORTADA-SENSORES.jpg\",\"keywords\":[\"puxadores de arm\u00e1rio\",\"puxadores de gaveta\"],\"articleSection\":[\"Not\u00edcias atuais\",\"Novidades\",\"Tend\u00eancias\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/actualidad-pt\\\/perto-de-um-local-inteligente-novos-sensores\\\/\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/actualidad-pt\\\/perto-de-um-local-inteligente-novos-sensores\\\/\",\"name\":\"Perto de um local inteligente. Novos sensores - Emuca Blogue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/actualidad-pt\\\/perto-de-um-local-inteligente-novos-sensores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/actualidad-pt\\\/perto-de-um-local-inteligente-novos-sensores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PORTADA-SENSORES.jpg\",\"datePublished\":\"2023-11-07T08:06:31+00:00\",\"dateModified\":\"2023-11-07T08:10:58+00:00\",\"description\":\"Surpreenda-se com a inova\u00e7\u00e3o dos sensores sem fios Wirly e Dot 2 para uma ilumina\u00e7\u00e3o inteligente e eficiente. Dete\u00e7\u00e3o de proximidade, interrutor sem fios e controlo t\u00e1til preciso num \u00fanico dispositivo. Adapt\u00e1vel a m\u00faltiplas aplica\u00e7\u00f5es, transforme a sua ilumina\u00e7\u00e3o com estilo!\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/actualidad-pt\\\/perto-de-um-local-inteligente-novos-sensores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/actualidad-pt\\\/perto-de-um-local-inteligente-novos-sensores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PORTADA-SENSORES.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PORTADA-SENSORES.jpg\",\"width\":900,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/\",\"name\":\"Emuca blog\",\"description\":\"No Blog informar-lhe-emos acerca das \u00faltimas novidades de produtos, actualidade no sector e ambientes. Mantenha-se informado em todo momento. \",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.emuca.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#organization\",\"name\":\"emuca\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-logo-emuca-menu.png\",\"contentUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-logo-emuca-menu.png\",\"width\":190,\"height\":190,\"caption\":\"emuca\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EmucaGroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/person\\\/81560ca037d9c1ed19744a85ef9cbe2a\",\"name\":\"Emuca\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/author\\\/emuca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perto de um local inteligente. Novos sensores - Emuca Blogue","description":"Surpreenda-se com a inova\u00e7\u00e3o dos sensores sem fios Wirly e Dot 2 para uma ilumina\u00e7\u00e3o inteligente e eficiente. Dete\u00e7\u00e3o de proximidade, interrutor sem fios e controlo t\u00e1til preciso num \u00fanico dispositivo. Adapt\u00e1vel a m\u00faltiplas aplica\u00e7\u00f5es, transforme a sua ilumina\u00e7\u00e3o com estilo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/","og_locale":"pt_PT","og_type":"article","og_title":"Perto de um local inteligente. Novos sensores - Emuca Blogue","og_description":"Surpreenda-se com a inova\u00e7\u00e3o dos sensores sem fios Wirly e Dot 2 para uma ilumina\u00e7\u00e3o inteligente e eficiente. Dete\u00e7\u00e3o de proximidade, interrutor sem fios e controlo t\u00e1til preciso num \u00fanico dispositivo. Adapt\u00e1vel a m\u00faltiplas aplica\u00e7\u00f5es, transforme a sua ilumina\u00e7\u00e3o com estilo!","og_url":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/","og_site_name":"Emuca blog","article_publisher":"https:\/\/www.facebook.com\/EmucaGroup","article_published_time":"2023-11-07T08:06:31+00:00","article_modified_time":"2023-11-07T08:10:58+00:00","og_image":[{"width":900,"height":500,"url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/10\/PORTADA-SENSORES.jpg","type":"image\/jpeg"}],"author":"Emuca","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Emuca","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/#article","isPartOf":{"@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/"},"author":{"name":"Emuca","@id":"https:\/\/blog.emuca.com\/#\/schema\/person\/81560ca037d9c1ed19744a85ef9cbe2a"},"headline":"Perto de um local inteligente. Novos sensores","datePublished":"2023-11-07T08:06:31+00:00","dateModified":"2023-11-07T08:10:58+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/"},"wordCount":574,"publisher":{"@id":"https:\/\/blog.emuca.com\/#organization"},"image":{"@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/10\/PORTADA-SENSORES.jpg","keywords":["puxadores de arm\u00e1rio","puxadores de gaveta"],"articleSection":["Not\u00edcias atuais","Novidades","Tend\u00eancias"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/","url":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/","name":"Perto de um local inteligente. Novos sensores - Emuca Blogue","isPartOf":{"@id":"https:\/\/blog.emuca.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/#primaryimage"},"image":{"@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/10\/PORTADA-SENSORES.jpg","datePublished":"2023-11-07T08:06:31+00:00","dateModified":"2023-11-07T08:10:58+00:00","description":"Surpreenda-se com a inova\u00e7\u00e3o dos sensores sem fios Wirly e Dot 2 para uma ilumina\u00e7\u00e3o inteligente e eficiente. Dete\u00e7\u00e3o de proximidade, interrutor sem fios e controlo t\u00e1til preciso num \u00fanico dispositivo. Adapt\u00e1vel a m\u00faltiplas aplica\u00e7\u00f5es, transforme a sua ilumina\u00e7\u00e3o com estilo!","inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/actualidad-pt\/perto-de-um-local-inteligente-novos-sensores\/#primaryimage","url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/10\/PORTADA-SENSORES.jpg","contentUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/10\/PORTADA-SENSORES.jpg","width":900,"height":500},{"@type":"WebSite","@id":"https:\/\/blog.emuca.com\/#website","url":"https:\/\/blog.emuca.com\/","name":"Emuca blog","description":"No Blog informar-lhe-emos acerca das \u00faltimas novidades de produtos, actualidade no sector e ambientes. Mantenha-se informado em todo momento. ","publisher":{"@id":"https:\/\/blog.emuca.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.emuca.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/blog.emuca.com\/#organization","name":"emuca","url":"https:\/\/blog.emuca.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.emuca.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/05\/cropped-logo-emuca-menu.png","contentUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/05\/cropped-logo-emuca-menu.png","width":190,"height":190,"caption":"emuca"},"image":{"@id":"https:\/\/blog.emuca.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EmucaGroup"]},{"@type":"Person","@id":"https:\/\/blog.emuca.com\/#\/schema\/person\/81560ca037d9c1ed19744a85ef9cbe2a","name":"Emuca","url":"https:\/\/blog.emuca.com\/pt-pt\/cat\/author\/emuca\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/posts\/51774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=51774"}],"version-history":[{"count":9,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/posts\/51774\/revisions"}],"predecessor-version":[{"id":52173,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/posts\/51774\/revisions\/52173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/media\/52324"}],"wp:attachment":[{"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=51774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=51774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=51774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}