{"id":33826,"date":"2022-05-09T15:26:15","date_gmt":"2022-05-09T13:26:15","guid":{"rendered":"http:\/\/blogs.emuca.com\/nblog\/?p=33826"},"modified":"2022-05-16T09:16:04","modified_gmt":"2022-05-16T07:16:04","slug":"paineis-para-mesa-ou-prateleiras-de-estante","status":"publish","type":"post","link":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/","title":{"rendered":"Pain\u00e9is para mesa ou prateleiras de estante"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"33826\" class=\"elementor elementor-33826 elementor-33461\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b4cdce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b4cdce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f72ba3f\" data-id=\"f72ba3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-512cdcb elementor-widget elementor-widget-text-editor\" data-id=\"512cdcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPainel desenhado <strong>para realizar uma mesa<\/strong>\u00a0de refei\u00e7\u00f5es, mesa de cozinha ou de escrit\u00f3rio, t\u00e3o s\u00f3 tem de adicionar umas patas aparafusadas. E consoante o tamanho, tamb\u00e9m se pode usar <strong>como prateleira ou estante<\/strong>, adicionando uns suportes de parede. \u00c9 ideal para personalizar m\u00f3veis conforme as suas necessidades, por exemplo realizar uma estante por medida, uma mesa de escrit\u00f3rio auxiliar ou uma escrivaninha para um quarto pequeno.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0932c7e elementor-widget elementor-widget-spacer\" data-id=\"0932c7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06e8c3b elementor-widget elementor-widget-hotspot\" data-id=\"06e8c3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;a8ad3f7&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/bases\\\/patas-de-mesa-pt\\\/acessorios-de-mesa\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/paineis-para-mesa-ou-prateleiras-de-estante-900-efeito-carvalho-madeira&quot;,&quot;is_external&quot;:&quot;on&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Painel para mesa\\r\\n\\r\\n&lt;img class=\\&quot;alignnone wp-image-33513 size-thumbnail\\&quot; src=\\&quot;http:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/8432393292533.main_-150x150.jpg\\&quot; alt=\\&quot;\\&quot; width=\\&quot;150\\&quot; height=\\&quot;150\\&quot; \\\/&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:69,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:44,&quot;sizes&quot;:[]},&quot;index&quot;:0,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null},{&quot;_id&quot;:&quot;a97dde9&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/bases\\\/rodas\\\/rodas-decorativas\\\/emuca-rodas-slip-2-com-placa-de-montagem\\\/emuca-rodas-com-placa-de-montagem-d-50mm-aco-e-plastico-cinza-4-ud&quot;,&quot;is_external&quot;:&quot;on&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Rodas Slip\\r\\n\\r\\n&lt;img class=\\&quot;alignnone wp-image-33724 size-thumbnail\\&quot; src=\\&quot;http:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/jcr_content-1-150x150.jpg\\&quot; alt=\\&quot;\\&quot; width=\\&quot;150\\&quot; height=\\&quot;150\\&quot; \\\/&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:51,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:85,&quot;sizes&quot;:[]},&quot;index&quot;:1,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null},{&quot;_id&quot;:&quot;4689012&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/bases\\\/patas-de-mesa-pt\\\/patas-60-pt\\\/emuca-patas-para-mesa-d-60-mm-em-aco\\\/emuca-patas-para-mesa-d-60-mm-regulaveis-710-730-mm-aco-cromado-4-ud&quot;,&quot;is_external&quot;:&quot;on&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Patas para mesa\\r\\n\\r\\n&lt;img class=\\&quot;alignnone wp-image-33734 size-thumbnail\\&quot; src=\\&quot;http:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/jcr_content-150x150.jpg\\&quot; alt=\\&quot;\\&quot; width=\\&quot;150\\&quot; height=\\&quot;150\\&quot; \\\/&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:79,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:69,&quot;sizes&quot;:[]},&quot;index&quot;:2,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null}],&quot;tooltip_position&quot;:&quot;bottom&quot;,&quot;tooltip_trigger&quot;:&quot;mouseenter&quot;,&quot;hotspot_sequenced_animation&quot;:&quot;no&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-in-out&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"890\" height=\"449\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-1-3.jpg\" class=\"attachment-full size-full wp-image-33627\" alt=\"\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-1-3.jpg 890w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-1-3-300x151.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-1-3-768x387.jpg 768w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/>\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-a8ad3f7  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/bases\/patas-de-mesa-pt\/acessorios-de-mesa\/paineis-para-mesa-ou-prateleiras-de-estante\/paineis-para-mesa-ou-prateleiras-de-estante-900-efeito-carvalho-madeira\" target=\"_blank\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\r\n\t\t\t\t\t\tPainel para mesa\r\n\r\n<img decoding=\"async\" class=\"alignnone wp-image-33513 size-thumbnail\" src=\"http:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292533.main_-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292533.main_-150x150.jpg 150w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292533.main_-300x300.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292533.main_-768x768.jpg 768w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292533.main_.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-a97dde9  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/bases\/rodas\/rodas-decorativas\/emuca-rodas-slip-2-com-placa-de-montagem\/emuca-rodas-com-placa-de-montagem-d-50mm-aco-e-plastico-cinza-4-ud\" target=\"_blank\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\r\n\t\t\t\t\t\tRodas Slip\r\n\r\n<img decoding=\"async\" class=\"alignnone wp-image-33724 size-thumbnail\" src=\"http:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content-1-150x150.jpg 150w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content-1-300x300.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content-1.jpg 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-4689012  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/bases\/patas-de-mesa-pt\/patas-60-pt\/emuca-patas-para-mesa-d-60-mm-em-aco\/emuca-patas-para-mesa-d-60-mm-regulaveis-710-730-mm-aco-cromado-4-ud\" target=\"_blank\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\r\n\t\t\t\t\t\tPatas para mesa\r\n\r\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33734 size-thumbnail\" src=\"http:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content-150x150.jpg 150w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content-300x300.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content.jpg 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d04f16 elementor-widget elementor-widget-spacer\" data-id=\"6d04f16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55278ad elementor-widget elementor-widget-text-editor\" data-id=\"55278ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCaracteriza-se por ser um <strong>produto sustent\u00e1vel e respeitador do meio-ambiente<\/strong> (certifica\u00e7\u00e3o FSC e PEFC). Em rela\u00e7\u00e3o \u00e0 reac\u00e7\u00e3o ao fogo, cumpre a classifica\u00e7\u00e3o D-s2, d0 em conformidade com a norma EN13986. Al\u00e9m disso est\u00e1 apto para o uso em interiores porque cumpre com a norma EN14322 (Pain\u00e9is derivados da madeira-Pain\u00e9is revestidos com melamina para utiliza\u00e7\u00e3o interior).\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af4ebe9 elementor-widget elementor-widget-spacer\" data-id=\"af4ebe9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd11bbe elementor-widget elementor-widget-hotspot\" data-id=\"cd11bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;74f5234&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/sistemas-de-montagem-parafusos-e-porcas\\\/acessorios-para-modulos-superiores\\\/suportes-para-prateleiras-de-parede\\\/emuca-suporte-squad-2-para-prateleira-de-madeira-o-vidro\\\/emuca-suporte-para-prateleira-de-madeira-vidro-espessura-4-38-mm-plastico-e-zamak-cinza-metalizado-2-ud&quot;,&quot;is_external&quot;:&quot;on&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Suporte Squad\\r\\n\\r\\n&lt;img class=\\&quot;alignnone wp-image-33744 size-thumbnail\\&quot; src=\\&quot;http:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/8432393000688.PT43-150x150.jpg\\&quot; alt=\\&quot;\\&quot; width=\\&quot;150\\&quot; height=\\&quot;150\\&quot; \\\/&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:80,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:46,&quot;sizes&quot;:[]},&quot;index&quot;:0,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null},{&quot;_id&quot;:&quot;2113df1&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/bases\\\/patas-de-mesa-pt\\\/acessorios-de-mesa\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/paineis-para-mesa-ou-prateleiras-de-estante-600-efeito-carvalho-madeira&quot;,&quot;is_external&quot;:&quot;on&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Painel para mesa\\r\\n\\r\\n&lt;img class=\\&quot;alignnone wp-image-33473 size-thumbnail\\&quot; src=\\&quot;http:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/8432393292557.main_-150x150.jpg\\&quot; alt=\\&quot;\\&quot; width=\\&quot;150\\&quot; height=\\&quot;150\\&quot; \\\/&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:58,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:40,&quot;sizes&quot;:[]},&quot;index&quot;:1,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null}],&quot;tooltip_position&quot;:&quot;bottom&quot;,&quot;tooltip_trigger&quot;:&quot;mouseenter&quot;,&quot;hotspot_sequenced_animation&quot;:&quot;no&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-in-out&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"890\" height=\"449\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-3.jpg\" class=\"attachment-full size-full wp-image-33584\" alt=\"\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-3.jpg 890w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-3-300x151.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-3-768x387.jpg 768w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/>\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-74f5234  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/sistemas-de-montagem-parafusos-e-porcas\/acessorios-para-modulos-superiores\/suportes-para-prateleiras-de-parede\/emuca-suporte-squad-2-para-prateleira-de-madeira-o-vidro\/emuca-suporte-para-prateleira-de-madeira-vidro-espessura-4-38-mm-plastico-e-zamak-cinza-metalizado-2-ud\" target=\"_blank\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\r\n\t\t\t\t\t\tSuporte Squad\r\n\r\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33744 size-thumbnail\" src=\"http:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393000688.PT43-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393000688.PT43-150x150.jpg 150w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393000688.PT43-300x300.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393000688.PT43.jpg 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-2113df1  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/bases\/patas-de-mesa-pt\/acessorios-de-mesa\/paineis-para-mesa-ou-prateleiras-de-estante\/paineis-para-mesa-ou-prateleiras-de-estante-600-efeito-carvalho-madeira\" target=\"_blank\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\r\n\t\t\t\t\t\tPainel para mesa\r\n\r\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33473 size-thumbnail\" src=\"http:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292557.main_-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292557.main_-150x150.jpg 150w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292557.main_-300x300.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292557.main_-768x768.jpg 768w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292557.main_.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-001babb elementor-widget elementor-widget-spacer\" data-id=\"001babb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49851d7 elementor-widget elementor-widget-text-editor\" data-id=\"49851d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEste painel est\u00e1 fabricado com <strong>materiais de elevada qualidade<\/strong>\u00a0que garantem uma longa vida \u00fatil, com uma maior resist\u00eancia aos danos. Estas propriedades evitam os riscos, o que significa que permanecer\u00e1 em perfeitas condi\u00e7\u00f5es durante muitos anos. \u00c9 f\u00e1cil de limpar, resistente \u00e0s manchas e disp\u00f5e de propriedades antibacterianas. Est\u00e1 fabricado em painel\u00a0 <strong>aglomerado de part\u00edculas<\/strong>\u00a0com superf\u00edcie de <strong>melamina<\/strong>\u00a0e est\u00e1 orlado pelos <strong>quatro lados com PVC<\/strong>. Al\u00e9m disso est\u00e1 dispon\u00edvel em dois acabamentos exclusivos, efeito carvalho ou branco de alta qualidade, ambos muito elegantes.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9cacf9 elementor-widget elementor-widget-spacer\" data-id=\"c9cacf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8ea8df elementor-widget elementor-widget-hotspot\" data-id=\"f8ea8df\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;972bb82&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/bases\\\/patas-de-mesa-pt\\\/acessorios-de-mesa\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/paineis-para-mesa-ou-prateleiras-de-estante-1150-efeito-carvalho-madeira&quot;,&quot;is_external&quot;:&quot;on&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Painel para mesa\\r\\n\\r\\n&lt;img class=\\&quot;alignnone wp-image-33493 size-thumbnail\\&quot; src=\\&quot;http:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/8432393292519.main_-150x150.jpg\\&quot; alt=\\&quot;\\&quot; width=\\&quot;150\\&quot; height=\\&quot;150\\&quot; \\\/&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:45,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:34,&quot;sizes&quot;:[]},&quot;index&quot;:0,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null},{&quot;_id&quot;:&quot;5726b4e&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.emuca.pt\\\/bases\\\/patas-de-mesa-pt\\\/patas-60-pt\\\/emuca-patas-para-mesa-d-60-mm-em-aco\\\/emuca-patas-para-mesa-d-60-mm-regulaveis-710-730-mm-aco-cromado-4-ud&quot;,&quot;is_external&quot;:&quot;on&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_tooltip_content&quot;:&quot;Patas para mesa\\r\\n\\r\\n&lt;img class=\\&quot;alignnone wp-image-33734 size-thumbnail\\&quot; src=\\&quot;http:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/jcr_content-150x150.jpg\\&quot; alt=\\&quot;\\&quot; width=\\&quot;150\\&quot; height=\\&quot;150\\&quot; \\\/&gt;&quot;,&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:67,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:39,&quot;sizes&quot;:[]},&quot;index&quot;:1,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_tooltip_position&quot;:&quot;no&quot;,&quot;hotspot_position&quot;:null}],&quot;tooltip_position&quot;:&quot;bottom&quot;,&quot;tooltip_trigger&quot;:&quot;mouseenter&quot;,&quot;hotspot_sequenced_animation&quot;:&quot;no&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-in-out&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"890\" height=\"449\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-2-3.jpg\" class=\"attachment-full size-full wp-image-33617\" alt=\"\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-2-3.jpg 890w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-2-3-300x151.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-2-3-768x387.jpg 768w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/>\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-972bb82  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/bases\/patas-de-mesa-pt\/acessorios-de-mesa\/paineis-para-mesa-ou-prateleiras-de-estante\/paineis-para-mesa-ou-prateleiras-de-estante-1150-efeito-carvalho-madeira\" target=\"_blank\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\r\n\t\t\t\t\t\tPainel para mesa\r\n\r\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33493 size-thumbnail\" src=\"http:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292519.main_-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292519.main_-150x150.jpg 150w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292519.main_-300x300.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292519.main_-768x768.jpg 768w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292519.main_.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-5726b4e  e-hotspot--position-left e-hotspot--position-top e-hotspot--link  e-hotspot--circle\" href=\"https:\/\/www.emuca.pt\/bases\/patas-de-mesa-pt\/patas-60-pt\/emuca-patas-para-mesa-d-60-mm-em-aco\/emuca-patas-para-mesa-d-60-mm-regulaveis-710-730-mm-aco-cromado-4-ud\" target=\"_blank\">\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button e-hotspot--expand\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__outer-circle\"><\/div>\r\n\t\t\t\t\t\t<div class=\"e-hotspot__inner-circle\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__tooltip  e-hotspot--tooltip-position e-hotspot--fade-in-out \" >\r\n\t\t\t\t\t\tPatas para mesa\r\n\r\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33734 size-thumbnail\" src=\"http:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content-150x150.jpg 150w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content-300x300.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/jcr_content.jpg 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t<\/a>\r\n\r\n\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56f8f1e elementor-widget elementor-widget-spacer\" data-id=\"56f8f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ad9c0f elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"2ad9c0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\r\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\r\n\t\t\t\t<div class=\"swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"8432393292519.main\" style=\"background-image: url(&#039;https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292519.main_.jpg&#039;)\">\r\n\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"8432393292489.main\" style=\"background-image: url(&#039;https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292489.main_.jpg&#039;)\">\r\n\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"8432393292533.main\" style=\"background-image: url(&#039;https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292533.main_.jpg&#039;)\">\r\n\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"8432393292526.main\" style=\"background-image: url(&#039;https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292526.main_.jpg&#039;)\">\r\n\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"8432393292557.main\" style=\"background-image: url(&#039;https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292557.main_.jpg&#039;)\">\r\n\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"8432393292540.main\" style=\"background-image: url(&#039;https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/8432393292540.main_.jpg&#039;)\">\r\n\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\r\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe46170 elementor-button-warning elementor-align-center elementor-widget elementor-widget-button\" data-id=\"fe46170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.emuca.pt\/bases\/patas-de-mesa-pt\/acessorios-de-mesa\/paineis-para-mesa-ou-prateleiras-de-estante\/paineis-para-mesa-ou-prateleiras-de-estante-900-efeito-carvalho-madeira\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver produtos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-186b621 elementor-widget elementor-widget-spacer\" data-id=\"186b621\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Painel desenhado para realizar uma mesa\u00a0de refei\u00e7\u00f5es, mesa de cozinha ou de escrit\u00f3rio, t\u00e3o s\u00f3 tem de adicionar umas patas aparafusadas. E consoante o tamanho, tamb\u00e9m se pode usar como prateleira ou estante, adicionando uns suportes de parede. \u00c9 ideal para personalizar m\u00f3veis conforme as suas necessidades, por exemplo realizar uma estante por medida, uma &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/\" class=\"more-link\">Continuar a ler <span class=\"screen-reader-text\">&#8220;Pain\u00e9is para mesa ou prateleiras de estante&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":33472,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[],"class_list":["post-33826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novidades","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pain\u00e9is para mesa ou prateleiras de estante - Emuca blog<\/title>\n<meta name=\"description\" content=\"Painel desenhado para realizar uma mesa de refei\u00e7\u00f5es, mesa de cozinha ou de escrit\u00f3rio, t\u00e3o s\u00f3 tem de adicionar umas patas aparafusadas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pain\u00e9is para mesa ou prateleiras de estante - Emuca blog\" \/>\n<meta property=\"og:description\" content=\"Painel desenhado para realizar uma mesa de refei\u00e7\u00f5es, mesa de cozinha ou de escrit\u00f3rio, t\u00e3o s\u00f3 tem de adicionar umas patas aparafusadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/\" \/>\n<meta property=\"og:site_name\" content=\"Emuca blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EmucaGroup\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T13:26:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-16T07:16:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-red.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emuca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emuca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/novidades\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/novidades\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/\"},\"author\":{\"name\":\"Emuca\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/person\\\/81560ca037d9c1ed19744a85ef9cbe2a\"},\"headline\":\"Pain\u00e9is para mesa ou prateleiras de estante\",\"datePublished\":\"2022-05-09T13:26:15+00:00\",\"dateModified\":\"2022-05-16T07:16:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/novidades\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/\"},\"wordCount\":260,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/novidades\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/EMUCA-TABLEROS-post-red.jpg\",\"articleSection\":[\"Novidades\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/novidades\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/novidades\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/\",\"name\":\"Pain\u00e9is para mesa ou prateleiras de estante - Emuca blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/novidades\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/novidades\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/EMUCA-TABLEROS-post-red.jpg\",\"datePublished\":\"2022-05-09T13:26:15+00:00\",\"dateModified\":\"2022-05-16T07:16:04+00:00\",\"description\":\"Painel desenhado para realizar uma mesa de refei\u00e7\u00f5es, mesa de cozinha ou de escrit\u00f3rio, t\u00e3o s\u00f3 tem de adicionar umas patas aparafusadas.\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/novidades\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/novidades\\\/paineis-para-mesa-ou-prateleiras-de-estante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/EMUCA-TABLEROS-post-red.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/EMUCA-TABLEROS-post-red.jpg\",\"width\":800,\"height\":450},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/\",\"name\":\"Emuca blog\",\"description\":\"No Blog informar-lhe-emos acerca das \u00faltimas novidades de produtos, actualidade no sector e ambientes. Mantenha-se informado em todo momento. \",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.emuca.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#organization\",\"name\":\"emuca\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-logo-emuca-menu.png\",\"contentUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-logo-emuca-menu.png\",\"width\":190,\"height\":190,\"caption\":\"emuca\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EmucaGroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/person\\\/81560ca037d9c1ed19744a85ef9cbe2a\",\"name\":\"Emuca\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/pt-pt\\\/cat\\\/author\\\/emuca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pain\u00e9is para mesa ou prateleiras de estante - Emuca blog","description":"Painel desenhado para realizar uma mesa de refei\u00e7\u00f5es, mesa de cozinha ou de escrit\u00f3rio, t\u00e3o s\u00f3 tem de adicionar umas patas aparafusadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/","og_locale":"pt_PT","og_type":"article","og_title":"Pain\u00e9is para mesa ou prateleiras de estante - Emuca blog","og_description":"Painel desenhado para realizar uma mesa de refei\u00e7\u00f5es, mesa de cozinha ou de escrit\u00f3rio, t\u00e3o s\u00f3 tem de adicionar umas patas aparafusadas.","og_url":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/","og_site_name":"Emuca blog","article_publisher":"https:\/\/www.facebook.com\/EmucaGroup","article_published_time":"2022-05-09T13:26:15+00:00","article_modified_time":"2022-05-16T07:16:04+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-red.jpg","type":"image\/jpeg"}],"author":"Emuca","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Emuca","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/#article","isPartOf":{"@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/"},"author":{"name":"Emuca","@id":"https:\/\/blog.emuca.com\/#\/schema\/person\/81560ca037d9c1ed19744a85ef9cbe2a"},"headline":"Pain\u00e9is para mesa ou prateleiras de estante","datePublished":"2022-05-09T13:26:15+00:00","dateModified":"2022-05-16T07:16:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/"},"wordCount":260,"publisher":{"@id":"https:\/\/blog.emuca.com\/#organization"},"image":{"@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-red.jpg","articleSection":["Novidades"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/","url":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/","name":"Pain\u00e9is para mesa ou prateleiras de estante - Emuca blog","isPartOf":{"@id":"https:\/\/blog.emuca.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/#primaryimage"},"image":{"@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-red.jpg","datePublished":"2022-05-09T13:26:15+00:00","dateModified":"2022-05-16T07:16:04+00:00","description":"Painel desenhado para realizar uma mesa de refei\u00e7\u00f5es, mesa de cozinha ou de escrit\u00f3rio, t\u00e3o s\u00f3 tem de adicionar umas patas aparafusadas.","inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.emuca.com\/pt-pt\/cat\/novidades\/paineis-para-mesa-ou-prateleiras-de-estante\/#primaryimage","url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-red.jpg","contentUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2022\/05\/EMUCA-TABLEROS-post-red.jpg","width":800,"height":450},{"@type":"WebSite","@id":"https:\/\/blog.emuca.com\/#website","url":"https:\/\/blog.emuca.com\/","name":"Emuca blog","description":"No Blog informar-lhe-emos acerca das \u00faltimas novidades de produtos, actualidade no sector e ambientes. Mantenha-se informado em todo momento. ","publisher":{"@id":"https:\/\/blog.emuca.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.emuca.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/blog.emuca.com\/#organization","name":"emuca","url":"https:\/\/blog.emuca.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.emuca.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/05\/cropped-logo-emuca-menu.png","contentUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/05\/cropped-logo-emuca-menu.png","width":190,"height":190,"caption":"emuca"},"image":{"@id":"https:\/\/blog.emuca.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EmucaGroup"]},{"@type":"Person","@id":"https:\/\/blog.emuca.com\/#\/schema\/person\/81560ca037d9c1ed19744a85ef9cbe2a","name":"Emuca","url":"https:\/\/blog.emuca.com\/pt-pt\/cat\/author\/emuca\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/posts\/33826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=33826"}],"version-history":[{"count":25,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/posts\/33826\/revisions"}],"predecessor-version":[{"id":34558,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/posts\/33826\/revisions\/34558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/media\/33472"}],"wp:attachment":[{"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=33826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=33826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.emuca.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=33826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}