{"id":46991,"date":"2023-01-26T15:42:19","date_gmt":"2023-01-26T14:42:19","guid":{"rendered":"http:\/\/blogs.emuca.com\/nblog\/?p=46991"},"modified":"2023-01-27T14:16:23","modified_gmt":"2023-01-27T13:16:23","slug":"systeme-coulissant-pour-les-armoires-flow","status":"publish","type":"post","link":"https:\/\/blog.emuca.com\/fr\/cat\/novedades\/systeme-coulissant-pour-les-armoires-flow\/","title":{"rendered":"Syst\u00e8me coulissant pour les armoires FLOW"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"46991\" class=\"elementor elementor-46991 elementor-46986\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0e2067 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0e2067\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b823fb\" data-id=\"3b823fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c75f20a elementor-widget elementor-widget-image\" data-id=\"c75f20a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"490\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/Flow-MAIL-5.gif\" class=\"attachment-full size-full wp-image-47716\" alt=\"\" sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea4bf23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea4bf23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48d453a\" data-id=\"48d453a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f170e79 elementor-widget elementor-widget-text-editor\" data-id=\"f170e79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Connaissez-vous notre syst\u00e8me coulissant Flow pour armoires ?<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a7d3bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a7d3bb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff7b94d\" data-id=\"ff7b94d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-868aa94 elementor-widget elementor-widget-text-editor\" data-id=\"868aa94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLe syst\u00e8me coulissant Flow est <strong>con\u00e7u pour l&rsquo;installation d&rsquo;armoires avec des portes soutenues <\/strong>et pour des <strong>portes pesant jusqu&rsquo;\u00e0 50 kg<\/strong>.\r\n\r\nLes chariots sont fabriqu\u00e9s en acier et en plastique avec des roues \u00e0 roulements \u00e0 billes qui font <strong>glisser le syst\u00e8me en douceur<\/strong>, seul un l\u00e9ger usinage est n\u00e9cessaire sur les portes, de la m\u00eame mani\u00e8re ces <strong>chariots ont un verrou de r\u00e9glage <\/strong>qui est actionn\u00e9 par un simple tour de vis en plus d&rsquo;avoir un <strong>r\u00e9glage en hauteur de 4 mm. <\/strong>\r\n\r\nEn outre, vous pouvez choisir entre <strong>deux types de verrouillage pour vos portes, soit <\/strong>une solution de type <strong>stop-frein, soit un syst\u00e8me de fermeture souple. <\/strong>Ce dernier est disponible en deux options de charge : 30 kg et 50 kg. Les deux options de verrouillage sont dissimul\u00e9es dans le m\u00eame rail.\r\n\r\n<strong>T\u00e9l\u00e9chargez le guide des accessoires Flow dont vous avez besoin pour l&rsquo;installation de votre bo\u00eetier.<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-593288b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"593288b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31e0493\" data-id=\"31e0493\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5037ba7 elementor-widget elementor-widget-text-editor\" data-id=\"5037ba7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>T\u00e9l\u00e9chargez le guide des accessoires Flow dont vous avez besoin pour l&rsquo;installation de votre bo\u00eetier.<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-198c76f elementor-widget elementor-widget-image\" data-id=\"198c76f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/resources.emuca.com\/fr\/catalogue-flow\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1175\" height=\"458\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/FLOWSUPCTA-ES.jpg\" class=\"attachment-full size-full wp-image-47261\" alt=\"\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/FLOWSUPCTA-ES.jpg 1175w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/FLOWSUPCTA-ES-300x117.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/FLOWSUPCTA-ES-1024x399.jpg 1024w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/FLOWSUPCTA-ES-768x299.jpg 768w\" sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d55068d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d55068d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24accf3\" data-id=\"24accf3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebc9c04 elementor-widget elementor-widget-spacer\" data-id=\"ebc9c04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddeb652 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddeb652\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df85327\" data-id=\"df85327\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-736ae20 elementor-widget elementor-widget-text-editor\" data-id=\"736ae20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Le syst\u00e8me coulissant Flow vous permet de choisir entre deux types d&rsquo;installation diff\u00e9rents. <\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd167e5 elementor-widget elementor-widget-text-editor\" data-id=\"cd167e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Le syst\u00e8me d&rsquo;\u00e9coulement est une surface encastr\u00e9e.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c8657e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c8657e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4569de4\" data-id=\"4569de4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df80a2f elementor-widget elementor-widget-text-editor\" data-id=\"df80a2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNous vous proposons diff\u00e9rents rails et finitions afin que vous puissiez choisir l&rsquo;option qui convient le mieux \u00e0 vos besoins en mati\u00e8re de mobilier.\r\n\r\nNous avons \u00e0 votre disposition les rails de <strong>surface Flow, <\/strong>ces rails sont tr\u00e8s <strong>faciles et rapides \u00e0 installer sur les meubles car il suffit de visser quelques clips pour <\/strong>les fixer en haut et en bas. Les rails seront l\u00e9g\u00e8rement visibles sur le meuble.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6165c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6165c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ea3a0d\" data-id=\"9ea3a0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f358945 elementor-widget elementor-widget-spacer\" data-id=\"f358945\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b48e2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b48e2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03106ad\" data-id=\"03106ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5273e8 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"d5273e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d5273e8\" data-elementor-lightbox-title=\"flow-sup3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwMzYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwMy5qcGciLCJzbGlkZXNob3ciOiJkNTI3M2U4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup3-300x300.jpg\" alt=\"flow-sup3\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d5273e8\" data-elementor-lightbox-title=\"flow-sup10\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwMDYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwMTAuanBnIiwic2xpZGVzaG93IjoiZDUyNzNlOCJ9\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup10-300x300.jpg\" alt=\"flow-sup10\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d5273e8\" data-elementor-lightbox-title=\"flow-sup2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwMjYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwMi5qcGciLCJzbGlkZXNob3ciOiJkNTI3M2U4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup2-300x300.jpg\" alt=\"flow-sup2\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d5273e8\" data-elementor-lightbox-title=\"flow-sup4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwNDYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwNC5qcGciLCJzbGlkZXNob3ciOiJkNTI3M2U4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup4-300x300.jpg\" alt=\"flow-sup4\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d5273e8\" data-elementor-lightbox-title=\"flow-sup9\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwOTYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwOS5qcGciLCJzbGlkZXNob3ciOiJkNTI3M2U4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup9-300x300.jpg\" alt=\"flow-sup9\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d5273e8\" data-elementor-lightbox-title=\"flow-sup1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwMTYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwMS5qcGciLCJzbGlkZXNob3ciOiJkNTI3M2U4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup1-300x300.jpg\" alt=\"flow-sup1\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d5273e8\" data-elementor-lightbox-title=\"flow-sup6\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwNjYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwNi5qcGciLCJzbGlkZXNob3ciOiJkNTI3M2U4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup6-300x300.jpg\" alt=\"flow-sup6\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d5273e8\" data-elementor-lightbox-title=\"flow-sup5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwNTYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwNS5qcGciLCJzbGlkZXNob3ciOiJkNTI3M2U4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup5-300x300.jpg\" alt=\"flow-sup5\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55bae3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55bae3c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ae6928\" data-id=\"6ae6928\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86331d9 elementor-widget elementor-widget-spacer\" data-id=\"86331d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49cb118 elementor-widget elementor-widget-text-editor\" data-id=\"49cb118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Montage en surface de l&rsquo;\u00e9coulement.<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e82b7d elementor-widget elementor-widget-video\" data-id=\"4e82b7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/W-f7TZy07Rs&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/emuca-flow-superficie.jpg&quot;,&quot;id&quot;:47363,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;video flow superficie&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Lire la vid\u00e9o sur video flow superficie\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-169eb2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"169eb2f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d8a86f\" data-id=\"7d8a86f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00a4c41 elementor-widget elementor-widget-spacer\" data-id=\"00a4c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72d42a3 elementor-widget elementor-widget-text-editor\" data-id=\"72d42a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa deuxi\u00e8me option, que vous connaissez d\u00e9j\u00e0, consiste \u00e0 utiliser <strong>le rail Flow pour l&rsquo;int\u00e9gration. Nous utiliserons le m\u00eame rail dans la partie sup\u00e9rieure et inf\u00e9rieure de l&rsquo;armoire, qui est cach\u00e9e dans le meuble<\/strong>.\r\n\r\nPour son montage, il suffit de r\u00e9aliser le m\u00eame usinage sur la partie sup\u00e9rieure et inf\u00e9rieure car nous utilisons le m\u00eame rail dans les meubles pour ce syst\u00e8me et il ne restera plus qu&rsquo;\u00e0 l&rsquo;installer.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-433ab73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"433ab73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0774f2\" data-id=\"d0774f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d85e88 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"8d85e88\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d85e88\" data-elementor-lightbox-title=\"flow-sup7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwNzYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwNy5qcGciLCJzbGlkZXNob3ciOiI4ZDg1ZTg4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup7-300x300.jpg\" alt=\"flow-sup7\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d85e88\" data-elementor-lightbox-title=\"flow-sup11\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcxNjUsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwMTEuanBnIiwic2xpZGVzaG93IjoiOGQ4NWU4OCJ9\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup11-300x300.jpg\" alt=\"flow-sup11\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d85e88\" data-elementor-lightbox-title=\"flow-sup9\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwOTYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwOS5qcGciLCJzbGlkZXNob3ciOiI4ZDg1ZTg4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup9-300x300.jpg\" alt=\"flow-sup9\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d85e88\" data-elementor-lightbox-title=\"flow-sup10\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwMDYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwMTAuanBnIiwic2xpZGVzaG93IjoiOGQ4NWU4OCJ9\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup10-300x300.jpg\" alt=\"flow-sup10\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d85e88\" data-elementor-lightbox-title=\"flow-sup6\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwNjYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwNi5qcGciLCJzbGlkZXNob3ciOiI4ZDg1ZTg4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup6-300x300.jpg\" alt=\"flow-sup6\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d85e88\" data-elementor-lightbox-title=\"flow-sup8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDcwODYsInVybCI6Imh0dHBzOlwvXC9ibG9nLmVtdWNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDFcL2Zsb3ctc3VwOC5qcGciLCJzbGlkZXNob3ciOiI4ZDg1ZTg4In0%3D\" href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-sup8-300x300.jpg\" alt=\"flow-sup8\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71b4e51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71b4e51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17de384\" data-id=\"17de384\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56e2fea elementor-widget elementor-widget-spacer\" data-id=\"56e2fea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aab240e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aab240e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50de6b6\" data-id=\"50de6b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-855cfa0 elementor-widget elementor-widget-text-editor\" data-id=\"855cfa0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Assemblage Flow.<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6176402 elementor-widget elementor-widget-video\" data-id=\"6176402\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/uXGZPTm31Fo&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Emuca-sliding-system-Flow.jpg&quot;,&quot;id&quot;:47373,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;video Flow encastrar&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/Emuca-sliding-system-Flow.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Lire la vid\u00e9o sur video Flow encastrar\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb23598 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb23598\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d1ead2\" data-id=\"9d1ead2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48f4690 elementor-widget elementor-widget-spacer\" data-id=\"48f4690\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c721c29 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c721c29\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b3f57c\" data-id=\"1b3f57c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e981863 elementor-widget elementor-widget-text-editor\" data-id=\"e981863\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Syst\u00e8mes de glissement de Flow en kit<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04ed052 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04ed052\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7fbcd1\" data-id=\"f7fbcd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1769e0 elementor-widget elementor-widget-text-editor\" data-id=\"c1769e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tVous pouvez trouver nos syst\u00e8mes <strong>Flow en kit <\/strong>pour r\u00e9aliser des armoires \u00e0 <strong>deux portes<\/strong>, il ne vous manque que les panneaux. En outre, le kit comprend deux dispositifs de fermeture douce pour chaque porte, offrant ainsi un syst\u00e8me d&rsquo;ouverture et de fermeture douce con\u00e7u pour les portes pesant jusqu&rsquo;\u00e0 30 kg.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cea7061 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cea7061\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-384e1ea\" data-id=\"384e1ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9364930 elementor-widget elementor-widget-image\" data-id=\"9364930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\/systeme-de-montage-en-surface-flowen-kit-pour-une-armoire-avec-2-portes-coulissantes-en-bois-avec-fermeture-souple\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"446\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-kit1.jpg\" class=\"attachment-large size-large wp-image-47432\" alt=\"\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-kit1.jpg 766w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-kit1-300x209.jpg 300w\" sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-019861e\" data-id=\"019861e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e64f639 elementor-widget elementor-widget-image\" data-id=\"e64f639\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.emuca.fr\/systeme-pour-portes-coulissantes\/systemes-pour-portes-coulissantes\/flow-fr\/emuca-systeme-flow-en-format-kit-pour-une-armoire-avec-2-portes-coulissantes-soutenues-en-bois-a-fermeture-amortie\/systeme-flow-pour-2-portes-coulissantes-en-bois-fermeture-amortie-panneaux-non-incluses-acier-et-aluminium-anodise\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"446\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-kit2-1.jpg\" class=\"attachment-large size-large wp-image-47455\" alt=\"\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-kit2-1.jpg 766w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/flow-kit2-1-300x209.jpg 300w\" sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Connaissez-vous notre syst\u00e8me coulissant Flow pour armoires ? Le syst\u00e8me coulissant Flow est con\u00e7u pour l&rsquo;installation d&rsquo;armoires avec des portes soutenues et pour des portes pesant jusqu&rsquo;\u00e0 50 kg. Les chariots sont fabriqu\u00e9s en acier et en plastique avec des roues \u00e0 roulements \u00e0 billes qui font glisser le syst\u00e8me en douceur, seul un l\u00e9ger &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blog.emuca.com\/fr\/cat\/novedades\/systeme-coulissant-pour-les-armoires-flow\/\" class=\"more-link\">Continuer la lecture <span class=\"screen-reader-text\"> \u00ab\u00a0Syst\u00e8me coulissant pour les armoires FLOW\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":47351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[1304,605],"class_list":["post-46991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades","tag-placard-a-portes-coulissantes-fr-2","tag-placards","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Syst\u00e8me coulissant Flow pour l&#039;assemblage d&#039;une armoire_Emuca<\/title>\n<meta name=\"description\" content=\"Le syst\u00e8me coulissant en applique Flow. Il est con\u00e7u pour l&#039;assemblage d&#039;armoires avec des portes soutenues et pour des portes pesant jusqu&#039;\u00e0 50 kg.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Syst\u00e8me coulissant Flow pour l&#039;assemblage d&#039;une armoire_Emuca\" \/>\n<meta property=\"og:description\" content=\"Le syst\u00e8me coulissant en applique Flow. Il est con\u00e7u pour l&#039;assemblage d&#039;armoires avec des portes soutenues et pour des portes pesant jusqu&#039;\u00e0 50 kg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/\" \/>\n<meta property=\"og:site_name\" content=\"Emuca blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EmucaGroup\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-26T14:42:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-27T13:16:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie-blog-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emuca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emuca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/\"},\"author\":{\"name\":\"Emuca\",\"@id\":\"https:\/\/blog.emuca.com\/#\/schema\/person\/81560ca037d9c1ed19744a85ef9cbe2a\"},\"headline\":\"Syst\u00e8me coulissant pour les armoires FLOW\",\"datePublished\":\"2023-01-26T14:42:19+00:00\",\"dateModified\":\"2023-01-27T13:16:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/\"},\"wordCount\":463,\"publisher\":{\"@id\":\"https:\/\/blog.emuca.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie-blog-1.jpg\",\"keywords\":[\"placard \u00e0 portes coulissantes\",\"placards\"],\"articleSection\":[\"Novedades\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/\",\"url\":\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/\",\"name\":\"Syst\u00e8me coulissant Flow pour l'assemblage d'une armoire_Emuca\",\"isPartOf\":{\"@id\":\"https:\/\/blog.emuca.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie-blog-1.jpg\",\"datePublished\":\"2023-01-26T14:42:19+00:00\",\"dateModified\":\"2023-01-27T13:16:23+00:00\",\"description\":\"Le syst\u00e8me coulissant en applique Flow. Il est con\u00e7u pour l'assemblage d'armoires avec des portes soutenues et pour des portes pesant jusqu'\u00e0 50 kg.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/#primaryimage\",\"url\":\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie-blog-1.jpg\",\"contentUrl\":\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie-blog-1.jpg\",\"width\":800,\"height\":450,\"caption\":\"Flow emuca superficie\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.emuca.com\/#website\",\"url\":\"https:\/\/blog.emuca.com\/\",\"name\":\"Emuca blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/blog.emuca.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.emuca.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.emuca.com\/#organization\",\"name\":\"emuca\",\"url\":\"https:\/\/blog.emuca.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/blog.emuca.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/05\/cropped-logo-emuca-menu.png\",\"contentUrl\":\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/05\/cropped-logo-emuca-menu.png\",\"width\":190,\"height\":190,\"caption\":\"emuca\"},\"image\":{\"@id\":\"https:\/\/blog.emuca.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EmucaGroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.emuca.com\/#\/schema\/person\/81560ca037d9c1ed19744a85ef9cbe2a\",\"name\":\"Emuca\",\"url\":\"https:\/\/blog.emuca.com\/fr\/cat\/author\/emuca\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Syst\u00e8me coulissant Flow pour l'assemblage d'une armoire_Emuca","description":"Le syst\u00e8me coulissant en applique Flow. Il est con\u00e7u pour l'assemblage d'armoires avec des portes soutenues et pour des portes pesant jusqu'\u00e0 50 kg.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/","og_locale":"fr_FR","og_type":"article","og_title":"Syst\u00e8me coulissant Flow pour l'assemblage d'une armoire_Emuca","og_description":"Le syst\u00e8me coulissant en applique Flow. Il est con\u00e7u pour l'assemblage d'armoires avec des portes soutenues et pour des portes pesant jusqu'\u00e0 50 kg.","og_url":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/","og_site_name":"Emuca blog","article_publisher":"https:\/\/www.facebook.com\/EmucaGroup","article_published_time":"2023-01-26T14:42:19+00:00","article_modified_time":"2023-01-27T13:16:23+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie-blog-1.jpg","type":"image\/jpeg"}],"author":"Emuca","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Emuca","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/#article","isPartOf":{"@id":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/"},"author":{"name":"Emuca","@id":"https:\/\/blog.emuca.com\/#\/schema\/person\/81560ca037d9c1ed19744a85ef9cbe2a"},"headline":"Syst\u00e8me coulissant pour les armoires FLOW","datePublished":"2023-01-26T14:42:19+00:00","dateModified":"2023-01-27T13:16:23+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/"},"wordCount":463,"publisher":{"@id":"https:\/\/blog.emuca.com\/#organization"},"image":{"@id":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie-blog-1.jpg","keywords":["placard \u00e0 portes coulissantes","placards"],"articleSection":["Novedades"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/","url":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/","name":"Syst\u00e8me coulissant Flow pour l'assemblage d'une armoire_Emuca","isPartOf":{"@id":"https:\/\/blog.emuca.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/#primaryimage"},"image":{"@id":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie-blog-1.jpg","datePublished":"2023-01-26T14:42:19+00:00","dateModified":"2023-01-27T13:16:23+00:00","description":"Le syst\u00e8me coulissant en applique Flow. Il est con\u00e7u pour l'assemblage d'armoires avec des portes soutenues et pour des portes pesant jusqu'\u00e0 50 kg.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.emuca.com\/fr\/cat\/nouveautes\/systeme-coulissant-pour-les-armoires-flow\/#primaryimage","url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie-blog-1.jpg","contentUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2023\/01\/emuca-flow-superficie-blog-1.jpg","width":800,"height":450,"caption":"Flow emuca superficie"},{"@type":"WebSite","@id":"https:\/\/blog.emuca.com\/#website","url":"https:\/\/blog.emuca.com\/","name":"Emuca blog","description":"","publisher":{"@id":"https:\/\/blog.emuca.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.emuca.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.emuca.com\/#organization","name":"emuca","url":"https:\/\/blog.emuca.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.emuca.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/05\/cropped-logo-emuca-menu.png","contentUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/05\/cropped-logo-emuca-menu.png","width":190,"height":190,"caption":"emuca"},"image":{"@id":"https:\/\/blog.emuca.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EmucaGroup"]},{"@type":"Person","@id":"https:\/\/blog.emuca.com\/#\/schema\/person\/81560ca037d9c1ed19744a85ef9cbe2a","name":"Emuca","url":"https:\/\/blog.emuca.com\/fr\/cat\/author\/emuca\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/posts\/46991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/comments?post=46991"}],"version-history":[{"count":23,"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/posts\/46991\/revisions"}],"predecessor-version":[{"id":47728,"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/posts\/46991\/revisions\/47728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/media\/47351"}],"wp:attachment":[{"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/media?parent=46991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/categories?post=46991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.emuca.com\/fr\/wp-json\/wp\/v2\/tags?post=46991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}