{"id":55305,"date":"2024-01-07T08:56:29","date_gmt":"2024-01-07T07:56:29","guid":{"rendered":"http:\/\/blogs.emuca.com\/nblog\/?p=55305"},"modified":"2024-03-07T08:57:29","modified_gmt":"2024-03-07T07:57:29","slug":"risques-de-reputation-lies-a-limpact-social-des-entreprises","status":"publish","type":"post","link":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/","title":{"rendered":"Risques de r\u00e9putation li\u00e9s \u00e0 l&rsquo;impact social des entreprises"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"55305\" class=\"elementor elementor-55305 elementor-55304\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f80085 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f80085\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c7e710a\" data-id=\"c7e710a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca3cbe8 elementor-widget elementor-widget-text-editor\" data-id=\"ca3cbe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De nos jours, et avec la vitesse \u00e0 laquelle l&rsquo;internet et les r\u00e9seaux sociaux nous permettent d&rsquo;acc\u00e9der imm\u00e9diatement \u00e0 toute information, il est important de prendre soin de la r\u00e9putation d&rsquo;une organisation, car il s&rsquo;agit d&rsquo;un actif intangible mais tr\u00e8s pr\u00e9cieux, qui peut \u00eatre difficile \u00e0 construire et pourtant extr\u00eamement facile \u00e0 perdre.<\/p>\n<p>Les risques de r\u00e9putation font donc r\u00e9f\u00e9rence \u00e0 la menace d&rsquo;atteinte \u00e0 l&rsquo;image et \u00e0 la perception publique d&rsquo;une entreprise, d&rsquo;une marque ou d&rsquo;un individu.<\/p>\n<p>Voici quelques-uns des facteurs qui peuvent influencer une mauvaise r\u00e9putation :<\/p>\n<p><em>Faute professionnelle <\/em>: comportement contraire \u00e0 l&rsquo;\u00e9thique, corruption, fraude ou toute autre forme de faute professionnelle.<\/p>\n<p><em>Probl\u00e8mes de qualit\u00e9 des produits ou des services <\/em>: si les produits ou les services d&rsquo;une entreprise ne r\u00e9pondent pas aux attentes ou, pire, causent du tort aux consommateurs, cela peut avoir un impact significatif sur la r\u00e9putation.<\/p>\n<p><em>Crise des relations industrielles <\/em>: les conflits avec les employ\u00e9s, les gr\u00e8ves ou les probl\u00e8mes de travail peuvent g\u00e9n\u00e9rer des perceptions n\u00e9gatives de l&rsquo;entreprise, en particulier si l&rsquo;entreprise est per\u00e7ue comme ne traitant pas ses employ\u00e9s de mani\u00e8re \u00e9quitable.<\/p>\n<p><em>Impact environnemental <\/em>: les pratiques commerciales qui nuisent \u00e0 l&rsquo;environnement peuvent avoir un effet n\u00e9gatif sur la r\u00e9putation d&rsquo;une entreprise, en particulier dans un contexte o\u00f9 la durabilit\u00e9 et la responsabilit\u00e9 environnementale sont de plus en plus valoris\u00e9es.<\/p>\n<p><em>Probl\u00e8mes juridiques <\/em>: les litiges, les amendes ou les probl\u00e8mes juridiques peuvent nuire \u00e0 la r\u00e9putation d&rsquo;une entreprise.<\/p>\n<p><em>Mauvaise gestion de la crise <\/em>: la mani\u00e8re dont une crise est g\u00e9r\u00e9e peut \u00eatre aussi importante, voire plus importante, que la crise elle-m\u00eame, et d\u00e9grader encore plus la r\u00e9putation si la r\u00e9ponse n&rsquo;est pas rapide et efficace.<\/p>\n<p><em>Probl\u00e8mes li\u00e9s aux m\u00e9dias sociaux <\/em>: les commentaires n\u00e9gatifs, les critiques virales ou les campagnes sur les m\u00e9dias sociaux peuvent rapidement diffuser des informations pr\u00e9judiciables.<\/p>\n<p><em>Concurrence d\u00e9loyale <\/em>: les actions des concurrents qui nuisent \u00e0 la r\u00e9putation d&rsquo;une entreprise, telles que les campagnes de diffamation ou les strat\u00e9gies d\u00e9loyales, repr\u00e9sentent \u00e9galement un risque.<\/p>\n<p>La gestion des risques de r\u00e9putation implique la mise en \u0153uvre de strat\u00e9gies proactives pour construire et maintenir une bonne r\u00e9putation, ainsi que des plans d&rsquo;urgence pour faire face \u00e0 toute situation susceptible d&rsquo;affecter n\u00e9gativement l&rsquo;image de l&rsquo;entreprise. La transparence, la responsabilit\u00e9 et une communication efficace sont les cl\u00e9s de la gestion des risques de r\u00e9putation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08d9b15 elementor-widget elementor-widget-image\" data-id=\"08d9b15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"356\" src=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/03\/sostenibilidad-emuca-23-24.jpg\" class=\"attachment-large size-large wp-image-55333\" alt=\"\" srcset=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/03\/sostenibilidad-emuca-23-24.jpg 900w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/03\/sostenibilidad-emuca-23-24-300x167.jpg 300w, https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/03\/sostenibilidad-emuca-23-24-768x427.jpg 768w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eb9c088 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb9c088\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-426e56f\" data-id=\"426e56f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23aa731 elementor-widget elementor-widget-text-editor\" data-id=\"23aa731\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Certains des risques suivants sont directement li\u00e9s \u00e0 l&rsquo;impact social de l&rsquo;entreprise :<\/p>\n<p><em>L&rsquo;\u00e9coblanchiment <\/em>: L&rsquo;accusation d&rsquo;<em>\u00e9coblanchiment <\/em>survient lorsqu&rsquo;une entreprise exag\u00e8re ou d\u00e9forme ses efforts environnementaux et sociaux afin de pr\u00e9senter une image plus favorable. Cela peut nuire \u00e0 la r\u00e9putation de l&rsquo;entreprise si elle est per\u00e7ue comme n&rsquo;\u00e9tant pas \u00e0 la hauteur de ses engagements.<\/p>\n<p><em>Probl\u00e8mes li\u00e9s \u00e0 la cha\u00eene d&rsquo;approvisionnement <\/em>: la d\u00e9couverte de pratiques contraires \u00e0 l&rsquo;\u00e9thique ou d&rsquo;impacts li\u00e9s \u00e0 des probl\u00e8mes sociaux tels que le travail des enfants ou des conditions de travail injustes peut avoir des cons\u00e9quences n\u00e9gatives sur la r\u00e9putation de l&rsquo;entreprise.<\/p>\n<p><em>Manque de <\/em>transparence : le manque de transparence dans les pratiques commerciales et les rapports sur l&rsquo;impact social peut susciter la m\u00e9fiance des <em>parties prenantes <\/em>et nuire \u00e0 la r\u00e9putation.<\/p>\n<p><em>Mise en \u0153uvre inefficace des <\/em>initiatives sociales : si les initiatives sociales d&rsquo;une entreprise n&rsquo;ont pas d&rsquo;impact positif r\u00e9el ou ne sont pas mises en \u0153uvre efficacement, la r\u00e9putation de l&rsquo;entreprise pourrait en souffrir.<\/p>\n<p><em>Manque de diversit\u00e9 et d&rsquo;inclusion en interne <\/em>: si une entreprise promeut des valeurs de diversit\u00e9 et d&rsquo;inclusion \u00e0 l&rsquo;ext\u00e9rieur mais ne les met pas en pratique en interne, elle risque d&rsquo;\u00eatre accus\u00e9e d&rsquo;hypocrisie en mati\u00e8re de r\u00e9putation.<\/p>\n<p><em>R\u00e9actions n\u00e9gatives aux parrainages ou aux partenariats <\/em>: les partenariats avec des organisations ou des causes sp\u00e9cifiques peuvent susciter des r\u00e9actions n\u00e9gatives si la perception de ces entit\u00e9s par le public change.<\/p>\n<p><em>Non-respect des normes \u00e9thiques <\/em>: si une entreprise est accus\u00e9e de violer les normes \u00e9thiques, que ce soit dans ses pratiques commerciales ou dans ses initiatives sociales, sa r\u00e9putation peut en souffrir.<\/p>\n<p><em>Changements d&rsquo;orientation strat\u00e9gique <\/em>: si une entreprise change brusquement d&rsquo;orientation sociale ou sans communication efficace, cela peut entra\u00eener une certaine confusion et un certain scepticisme quant \u00e0 ses intentions et \u00e0 ses engagements en mati\u00e8re sociale.<\/p>\n<p>L&rsquo;EMUCA a mis \u00e0 la disposition des parties int\u00e9ress\u00e9es un canal de communication \u00e9thique pour recevoir toute information impliquant un non-respect de la l\u00e9gislation en vigueur et a \u00e9galement \u00e9tabli une politique de communication.<\/p>\n<p>En outre, depuis 2006, nous sommes certifi\u00e9s \u00ab\u00a0Entreprise familiale responsable\u00a0\u00bb, un certificat qui reconna\u00eet notre engagement en faveur de politiques et d&rsquo;initiatives qui garantissent l&rsquo;\u00e9quilibre entre vie professionnelle et vie priv\u00e9e et l&rsquo;\u00e9galit\u00e9 entre les employ\u00e9s. Enfin, nous sommes tr\u00e8s attach\u00e9s \u00e0 notre strat\u00e9gie de d\u00e9veloppement durable.<\/p>\n<p>Une gestion efficace de ces risques a les cons\u00e9quences positives suivantes :<\/p>\n<ul>\n<li>Une confiance et une cr\u00e9dibilit\u00e9 accrues, en faisant preuve d&rsquo;un comportement \u00e9thique.<\/li>\n<li>La fid\u00e9lit\u00e9 des clients, qui per\u00e7oivent que l&rsquo;entreprise leur inspire confiance.<\/li>\n<li>Valeur de la marque, avec une position concurrentielle plus forte.<\/li>\n<li>Attirer les talents, car ils sont bien valoris\u00e9s et ont un impact positif.<\/li>\n<li>Renforcer les relations avec les parties prenantes<\/li>\n<li>R\u00e9silience aux crises gr\u00e2ce \u00e0 une meilleure pr\u00e9paration pour une gestion plus efficace<\/li>\n<li>Diff\u00e9renciation concurrentielle, en se d\u00e9marquant de la concurrence en attirant les consommateurs.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0fe119 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0fe119\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ce93a4\" data-id=\"0ce93a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abefaaa elementor-widget elementor-widget-html\" data-id=\"abefaaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-ea7c6c7f-91e2-44ae-b91a-be0c479bf6f9\"><span class=\"hs-cta-node hs-cta-ea7c6c7f-91e2-44ae-b91a-be0c479bf6f9\" id=\"hs-cta-ea7c6c7f-91e2-44ae-b91a-be0c479bf6f9\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/4071763\/ea7c6c7f-91e2-44ae-b91a-be0c479bf6f9\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-ea7c6c7f-91e2-44ae-b91a-be0c479bf6f9\" style=\"border-width:0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4071763\/ea7c6c7f-91e2-44ae-b91a-be0c479bf6f9.png\"  alt=\"Nueva llamada a la acci\u00f3n\"\/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(4071763, 'ea7c6c7f-91e2-44ae-b91a-be0c479bf6f9', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>De nos jours, et avec la vitesse \u00e0 laquelle l&rsquo;internet et les r\u00e9seaux sociaux nous permettent d&rsquo;acc\u00e9der imm\u00e9diatement \u00e0 toute information, il est important de prendre soin de la r\u00e9putation d&rsquo;une organisation, car il s&rsquo;agit d&rsquo;un actif intangible mais tr\u00e8s pr\u00e9cieux, qui peut \u00eatre difficile \u00e0 construire et pourtant extr\u00eamement facile \u00e0 perdre. Les risques &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> \u00ab\u00a0Risques de r\u00e9putation li\u00e9s \u00e0 l&rsquo;impact social des entreprises\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":55324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[812,1252],"tags":[],"class_list":["post-55305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dernieres-nouvelles-be","category-style-de-vie-be","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Risques de r\u00e9putation li\u00e9s \u00e0 l&#039;impact social des entreprises - Emuca Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risques de r\u00e9putation li\u00e9s \u00e0 l&#039;impact social des entreprises - Emuca Blog\" \/>\n<meta property=\"og:description\" content=\"De nos jours, et avec la vitesse \u00e0 laquelle l&rsquo;internet et les r\u00e9seaux sociaux nous permettent d&rsquo;acc\u00e9der imm\u00e9diatement \u00e0 toute information, il est important de prendre soin de la r\u00e9putation d&rsquo;une organisation, car il s&rsquo;agit d&rsquo;un actif intangible mais tr\u00e8s pr\u00e9cieux, qui peut \u00eatre difficile \u00e0 construire et pourtant extr\u00eamement facile \u00e0 perdre. Les risques &hellip; Continue reading &quot;Risques de r\u00e9putation li\u00e9s \u00e0 l&rsquo;impact social des entreprises&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/\" \/>\n<meta property=\"og:site_name\" content=\"Emuca Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EmucaGroup\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-07T07:56:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T07:57:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/03\/sostenibilidad-emuca-23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emuca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emuca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/dernieres-nouvelles-be\\\/risques-de-reputation-lies-a-limpact-social-des-entreprises\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/dernieres-nouvelles-be\\\/risques-de-reputation-lies-a-limpact-social-des-entreprises\\\/\"},\"author\":{\"name\":\"Emuca\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/person\\\/81560ca037d9c1ed19744a85ef9cbe2a\"},\"headline\":\"Risques de r\u00e9putation li\u00e9s \u00e0 l&rsquo;impact social des entreprises\",\"datePublished\":\"2024-01-07T07:56:29+00:00\",\"dateModified\":\"2024-03-07T07:57:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/dernieres-nouvelles-be\\\/risques-de-reputation-lies-a-limpact-social-des-entreprises\\\/\"},\"wordCount\":984,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/dernieres-nouvelles-be\\\/risques-de-reputation-lies-a-limpact-social-des-entreprises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/sostenibilidad-emuca-23.jpg\",\"articleSection\":[\"Derni\u00e8res nouvelles\",\"Style de vie\"],\"inLanguage\":\"fr-BE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/dernieres-nouvelles-be\\\/risques-de-reputation-lies-a-limpact-social-des-entreprises\\\/\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/dernieres-nouvelles-be\\\/risques-de-reputation-lies-a-limpact-social-des-entreprises\\\/\",\"name\":\"Risques de r\u00e9putation li\u00e9s \u00e0 l'impact social des entreprises - Emuca Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/dernieres-nouvelles-be\\\/risques-de-reputation-lies-a-limpact-social-des-entreprises\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/dernieres-nouvelles-be\\\/risques-de-reputation-lies-a-limpact-social-des-entreprises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/sostenibilidad-emuca-23.jpg\",\"datePublished\":\"2024-01-07T07:56:29+00:00\",\"dateModified\":\"2024-03-07T07:57:29+00:00\",\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/dernieres-nouvelles-be\\\/risques-de-reputation-lies-a-limpact-social-des-entreprises\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/dernieres-nouvelles-be\\\/risques-de-reputation-lies-a-limpact-social-des-entreprises\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/sostenibilidad-emuca-23.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/sostenibilidad-emuca-23.jpg\",\"width\":900,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/\",\"name\":\"Emuca Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.emuca.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#organization\",\"name\":\"emuca\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-logo-emuca-menu.png\",\"contentUrl\":\"https:\\\/\\\/blog.emuca.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-logo-emuca-menu.png\",\"width\":190,\"height\":190,\"caption\":\"emuca\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EmucaGroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.emuca.com\\\/#\\\/schema\\\/person\\\/81560ca037d9c1ed19744a85ef9cbe2a\",\"name\":\"Emuca\",\"url\":\"https:\\\/\\\/blog.emuca.com\\\/be\\\/cat\\\/author\\\/emuca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risques de r\u00e9putation li\u00e9s \u00e0 l'impact social des entreprises - Emuca Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/","og_locale":"fr_FR","og_type":"article","og_title":"Risques de r\u00e9putation li\u00e9s \u00e0 l'impact social des entreprises - Emuca Blog","og_description":"De nos jours, et avec la vitesse \u00e0 laquelle l&rsquo;internet et les r\u00e9seaux sociaux nous permettent d&rsquo;acc\u00e9der imm\u00e9diatement \u00e0 toute information, il est important de prendre soin de la r\u00e9putation d&rsquo;une organisation, car il s&rsquo;agit d&rsquo;un actif intangible mais tr\u00e8s pr\u00e9cieux, qui peut \u00eatre difficile \u00e0 construire et pourtant extr\u00eamement facile \u00e0 perdre. Les risques &hellip; Continue reading \"Risques de r\u00e9putation li\u00e9s \u00e0 l&rsquo;impact social des entreprises\"","og_url":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/","og_site_name":"Emuca Blog","article_publisher":"https:\/\/www.facebook.com\/EmucaGroup","article_published_time":"2024-01-07T07:56:29+00:00","article_modified_time":"2024-03-07T07:57:29+00:00","og_image":[{"width":900,"height":500,"url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/03\/sostenibilidad-emuca-23.jpg","type":"image\/jpeg"}],"author":"Emuca","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Emuca","Dur\u00e9e de lecture est.":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/#article","isPartOf":{"@id":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/"},"author":{"name":"Emuca","@id":"https:\/\/blog.emuca.com\/#\/schema\/person\/81560ca037d9c1ed19744a85ef9cbe2a"},"headline":"Risques de r\u00e9putation li\u00e9s \u00e0 l&rsquo;impact social des entreprises","datePublished":"2024-01-07T07:56:29+00:00","dateModified":"2024-03-07T07:57:29+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/"},"wordCount":984,"publisher":{"@id":"https:\/\/blog.emuca.com\/#organization"},"image":{"@id":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/03\/sostenibilidad-emuca-23.jpg","articleSection":["Derni\u00e8res nouvelles","Style de vie"],"inLanguage":"fr-BE"},{"@type":"WebPage","@id":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/","url":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/","name":"Risques de r\u00e9putation li\u00e9s \u00e0 l'impact social des entreprises - Emuca Blog","isPartOf":{"@id":"https:\/\/blog.emuca.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/#primaryimage"},"image":{"@id":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/03\/sostenibilidad-emuca-23.jpg","datePublished":"2024-01-07T07:56:29+00:00","dateModified":"2024-03-07T07:57:29+00:00","inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/blog.emuca.com\/be\/cat\/dernieres-nouvelles-be\/risques-de-reputation-lies-a-limpact-social-des-entreprises\/#primaryimage","url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/03\/sostenibilidad-emuca-23.jpg","contentUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/03\/sostenibilidad-emuca-23.jpg","width":900,"height":500},{"@type":"WebSite","@id":"https:\/\/blog.emuca.com\/#website","url":"https:\/\/blog.emuca.com\/","name":"Emuca Blog","description":"","publisher":{"@id":"https:\/\/blog.emuca.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.emuca.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/blog.emuca.com\/#organization","name":"emuca","url":"https:\/\/blog.emuca.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/blog.emuca.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/05\/cropped-logo-emuca-menu.png","contentUrl":"https:\/\/blog.emuca.com\/wp-content\/uploads\/2024\/05\/cropped-logo-emuca-menu.png","width":190,"height":190,"caption":"emuca"},"image":{"@id":"https:\/\/blog.emuca.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EmucaGroup"]},{"@type":"Person","@id":"https:\/\/blog.emuca.com\/#\/schema\/person\/81560ca037d9c1ed19744a85ef9cbe2a","name":"Emuca","url":"https:\/\/blog.emuca.com\/be\/cat\/author\/emuca\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/posts\/55305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/comments?post=55305"}],"version-history":[{"count":8,"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/posts\/55305\/revisions"}],"predecessor-version":[{"id":55374,"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/posts\/55305\/revisions\/55374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/media\/55324"}],"wp:attachment":[{"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/media?parent=55305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/categories?post=55305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.emuca.com\/be\/wp-json\/wp\/v2\/tags?post=55305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}